{"id":92,"date":"2026-03-15T22:59:43","date_gmt":"2026-03-15T22:59:43","guid":{"rendered":"https:\/\/muyano.com\/elcanaldelwason\/?page_id=92"},"modified":"2026-03-20T12:02:42","modified_gmt":"2026-03-20T12:02:42","slug":"videos-del-canal","status":"publish","type":"page","link":"https:\/\/muyano.com\/elcanaldelwason\/videos-del-canal\/","title":{"rendered":"Videos del Canal"},"content":{"rendered":"\n<div class=\"inherit-container-width wp-block-group alignfull is-style-ext-preset--group--natural-1--section ext-animate--on has-background-background-color has-background is-layout-constrained wp-container-core-group-is-layout-f72f1611 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--70);padding-bottom:var(--wp--preset--spacing--70)\">\n<div class=\"wp-block-group alignwide ext-is-logical-start ext-animate--on is-content-justification-left is-layout-constrained wp-container-core-group-is-layout-6729bdbe wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading ext-animate--on\">Zona de Videos del Wason: Donde el Humor Absurdo y el Vicio se Encuentran<\/h2>\n\n\n\n<p class=\"has-text-align-left ext-animate--on\">En el vasto oc\u00e9ano de contenido que es internet en 2026, encontrar un lugar que combine la irreverencia, la nostalgia y el humor sin filtros es como encontrar un \u00abglitch\u00bb de dinero infinito en un RPG: dif\u00edcil, pero sumamente satisfactorio. Si ya le diste duro a los <strong>Juegos de Mate<\/strong> en nuestra web, si ya recorriste nuestros informes sobre los mejores <strong>fangames gratuitos<\/strong>, entonces llegaste al momento de hacer el \u00abrecreo del guerrero\u00bb. Bienvenidos a la <strong>Zona de Videos de El Canal del Wason<\/strong>.<\/p>\n<\/div>\n\n\n\t\t\n\t\t<div id=\"gsyt_1\" data-yt-slider='{&quot;speed&quot;:1000,&quot;isAutoplay&quot;:true,&quot;autoplayDelay&quot;:1000,&quot;loop&quot;:true,&quot;pauseOnHover&quot;:true,&quot;ticker&quot;:false,&quot;reverseDirection&quot;:false,&quot;navs&quot;:true,&quot;navs_pos&quot;:&quot;carousel-navs-pos--center&quot;,&quot;dots&quot;:true,&quot;spaceBetween&quot;:10,&quot;slidesPerGroup&quot;:1,&quot;desktopItems&quot;:1,&quot;tabletItems&quot;:3,&quot;mobileItems&quot;:1,&quot;gsp_navs_style&quot;:&quot;nav--style-08&quot;,&quot;gsp_dots_style&quot;:&quot;dot--style-01&quot;}' class=\"wrap gs_ytgallery_area style-01 gs_yt_slider gsyt-has--navs nav--style-08 carousel-navs-pos--center gsyt-has--dots dot--style-01\">\n\n\t\t\t\n<div class=\"gs-containeer\">\n\n    <div class=\"gs-roow clearfix gs_youtubegalleries\" style=\"row-gap: 30px\">\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_lLyBGj6NcyE_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/lLyBGj6NcyE\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Tony explica &quot;la burbuja de la IA&quot; con una emotiva experiencia\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:24    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_lLyBGj6NcyE_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/lLyBGj6NcyE\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_s1aq5QGd-j0_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/s1aq5QGd-j0\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Thony y Thor se van a las manos \ud83e\udd4a | Avengers La Era de Ultr\u00f3n\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:34    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_s1aq5QGd-j0_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/s1aq5QGd-j0\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_5DzA21Cskec_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/5DzA21Cskec\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Robert Downey Jr. y el DESASTRE de las sillas vac\u00edas \ud83e\udd26\u200d\u2642\ufe0f\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:28    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_5DzA21Cskec_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/5DzA21Cskec\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_sh0w4dWtinw_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/sh0w4dWtinw\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"\u00bfQu\u00e9 pasa en el Show de Truman?\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:36    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_sh0w4dWtinw_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/sh0w4dWtinw\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_JreFbHJmiCE_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/JreFbHJmiCE\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"la Matrix se vuelve peronista \u270c\ufe0f\ud83d\udc8a\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:46    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_JreFbHJmiCE_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/JreFbHJmiCE\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_F5PoccKVw24_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/F5PoccKVw24\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Tr\u00e1iler2: Avengers DOOMSDAY #avengersdoomsday  #robertdowneyjr  #marvel  #avengers   #doctordoom\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:46    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_F5PoccKVw24_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/F5PoccKVw24\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_T5lgHZPwK9w_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/T5lgHZPwK9w\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Nuevo Tr\u00e1iler: Avengers DOOMSDAY#AvengersDoomsday #RobertDowneyJr #Marvel #avengers  #doctordoom\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:41    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_T5lgHZPwK9w_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/T5lgHZPwK9w\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_Efkd1fu6eW0_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/Efkd1fu6eW0\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Cumbres Borrascosas: El tr\u00e1iler que NO quieren que veas (Cumbre Babosas)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:14    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_Efkd1fu6eW0_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/Efkd1fu6eW0\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_2z-Wz-PgdFA_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/2z-Wz-PgdFA\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Nuevo Tr\u00e1iler de HE-MAN: Escenas In\u00e9ditas  y un Final Inesperado\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:54    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_2z-Wz-PgdFA_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/2z-Wz-PgdFA\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_cM8Z7M1ms7g_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/cM8Z7M1ms7g\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Cumbres Borrascosas: El tr\u00e1iler de Cumbre Babosas\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:13    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_cM8Z7M1ms7g_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/cM8Z7M1ms7g\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_sj2mqD0I9qU_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/sj2mqD0I9qU\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"R\u00c1PIDO Y GILAZOS \ud83d\ude02\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:32    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_sj2mqD0I9qU_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/sj2mqD0I9qU\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_NDzpqISpXn8_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/NDzpqISpXn8\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"R\u00c1PIDO Y GILAZOS \ud83d\ude02 (Parodia R\u00e1pido y Furioso)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:32    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_NDzpqISpXn8_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/NDzpqISpXn8\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_UKEKsaqeM74_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/UKEKsaqeM74\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Johnny Cage vs Scorpion: La Batalla de Baile #mortalkombat1  #johnnycage #scorpion  #dancebattle\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:18    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_UKEKsaqeM74_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/UKEKsaqeM74\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_axHqOY4U6aQ_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/axHqOY4U6aQ\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"La Verdadera (y Confusa) Familia de Darth Vader\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:45    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_axHqOY4U6aQ_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/axHqOY4U6aQ\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_YvNGCzxMyjQ_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/YvNGCzxMyjQ\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"\u00a1Todos levantan el martillo de Thor... MENOS THOR! (Parodia Avengers)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:26    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_YvNGCzxMyjQ_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/YvNGCzxMyjQ\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_z01TMRLk5Jk_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/z01TMRLk5Jk\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Wolverine vs Magneto: Una historia de amor (y vigas)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:33    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_z01TMRLk5Jk_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/z01TMRLk5Jk\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_i0q5tie7NQs_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/i0q5tie7NQs\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"El Exorcista de las Flatulencias\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:40    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_i0q5tie7NQs_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/i0q5tie7NQs\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_ATQHDDg8Dt4_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/ATQHDDg8Dt4\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"\u00a1No solo Will Smith! TODOS los que golpearon a Chris Rock \ud83d\udc7d\ud83d\udc19\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:01    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_ATQHDDg8Dt4_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/ATQHDDg8Dt4\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_nDiUi__bBn4_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/nDiUi__bBn4\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Brad Pitt es NOQUEADO por una X-Men (Parodia Joe Black)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:03    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_nDiUi__bBn4_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/nDiUi__bBn4\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-1 gs-col-md-3 gs-col-sm-6 gs-col-xs-1\">\n                <div class=\"gs-ytube--single-item\">\n                    <div class=\"gs-ytube--area_top\">\n\n                        <!-- Video Thumbnail -->\n                        \n<a href=\"#gs_ytgal_popup_sbuoKjL3tXc_1\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/sbuoKjL3tXc\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"\u00bfQu\u00e9 pasa en el Show de Truman? (Parodia con Dinosaurios y el Titanic)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <svg width=\"60\" height=\"42\"><use xlink:href=\"#gs_youtube_play_icon\"\/><\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:45    <\/span>\n\n<\/a>\n\n                    <\/div>\n                <\/div>\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_sbuoKjL3tXc_1\" class=\"gs_ytgal_popup_shortcode_1 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/sbuoKjL3tXc\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n            <\/div>\n\n        \n    <\/div>\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t<style>#gsyt_1 .items .gs-ytgal-name a{font-size:13px !important}#gsyt_1 .items .gs-ytgal-name a{color:#000!important}#gsyt_1 .items .gs-ytgal-name a{font-weight:normal!important}#gsyt_1 .items .gs-ytgal-name a{font-style:normal!important}<\/style>\n\n\n\n<p class=\"ext-animate--on\">\ud83c\udfac \u00a1Bienvenidos a la Zona de Videos!<\/p>\n\n\n\n<p class=\"ext-animate--on\">Si ya le diste duro a los minijuegos y necesit\u00e1s una pausa, llegaste al lugar indicado. Ac\u00e1 vas a encontrar una selecci\u00f3n con lo mejor de <strong>El Canal del Wason<\/strong>, el rinc\u00f3n donde la locura y el humor son la regla principal.<\/p>\n\n\n\n<p class=\"ext-animate--on\"><strong>\u00bfQu\u00e9 vas a encontrar en el canal?<\/strong><\/p>\n\n\n\n<style>\n  .wason-yt-moderno {\n    display: flex;\n    justify-content: center;\n    align-items: center;\n    margin: 32px auto; \/* Espacio arriba y abajo, centrado autom\u00e1tico *\/\n    max-width: 100%;\n  }\n  .wason-yt-moderno a {\n    display: inline-flex;\n    align-items: center;\n    gap: 10px; \/* Separaci\u00f3n entre el \u00edcono y el texto *\/\n    background: linear-gradient(135deg, #ff0000, #cc0000); \/* Rojo YouTube con volumen *\/\n    color: #ffffff !important; \/* Texto blanco forzado para que tu tema no lo cambie *\/\n    font-family: \"Inter\", system-ui, -apple-system, sans-serif;\n    font-size: 18px;\n    font-weight: 700;\n    text-decoration: none !important;\n    padding: 16px 32px;\n    border-radius: 50px; \/* Forma de pastilla *\/\n    box-shadow: 0 6px 16px rgba(255, 0, 0, 0.25); \/* Sombra roja flotante *\/\n    transition: all 0.3s ease; \/* Animaci\u00f3n suave *\/\n  }\n  .wason-yt-moderno a:hover {\n    transform: translateY(-3px) scale(1.02); \/* Se levanta y agranda un poquito *\/\n    box-shadow: 0 10px 24px rgba(255, 0, 0, 0.4); \/* La sombra se intensifica *\/\n  }\n  .wason-yt-moderno a:active {\n    transform: translateY(1px); \/* Efecto de \"hundirse\" al hacer clic real *\/\n    box-shadow: 0 4px 10px rgba(255, 0, 0, 0.2);\n  }\n  .yt-icono {\n    font-size: 20px;\n    line-height: 1;\n  }\n<\/style>\n\n<div class=\"wason-yt-moderno\">\n  <a href=\"https:\/\/www.youtube.com\/@ElCanaldelWason?sub_confirmation=1\" target=\"_blank\" rel=\"noopener noreferrer\">\n    <span class=\"yt-icono\">\u25b6<\/span> \u00a1Suscribite a El Canal del Wason!\n  <\/a>\n<\/div>\n<\/div>\n\n\n\n<div class=\"inherit-container-width wp-block-group alignfull is-style-ext-preset--group--natural-1--section ext-animate--on has-tertiary-background-color has-background is-layout-constrained wp-container-core-group-is-layout-e955bbaf wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--70);padding-bottom:var(--wp--preset--spacing--70)\">\n<h2 class=\"wp-block-heading has-text-align-center ext-animate--on\">Explora videos divertidos y \u00fanicos.<\/h2>\n\n\n\t\t\n\t\t<div id=\"gsyt_2\" data-yt-slider='' class=\"wrap gs_ytgallery_area horizontal-01 gs_yt_grid\">\n\n\t\t\t\n<div class=\"gs-containeer\">\n    <div class=\"gs-roow clearfix gs_youtubegalleries\" style=\"row-gap: 30px\">\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_lLyBGj6NcyE_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/lLyBGj6NcyE\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Tony explica &quot;la burbuja de la IA&quot; con una emotiva experiencia\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:24    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_lLyBGj6NcyE_2\" class=\"gs-ytube--link\"> Tony explica &quot;la burbuja de la IA&quot; con una emotiva... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >Lo que Marvel te ocult\u00f3 en Avengers La Era de Ultr\u00f3n: Thony contra Thor \ud83d\ude02\nDale play y enterate de la verdad que los directores no quisieron mostrarte!\n\n\ud83d\udc47 Si el video te sac\u00f3 una risa:\n\ud83d\udc4d Dej\u00e1 tu like (ayuda un mont\u00f3n).\n\ud83d\udd14...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            75 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            1K        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            2\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_lLyBGj6NcyE_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/lLyBGj6NcyE\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_s1aq5QGd-j0_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/s1aq5QGd-j0\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Thony y Thor se van a las manos \ud83e\udd4a | Avengers La Era de Ultr\u00f3n\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:34    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_s1aq5QGd-j0_2\" class=\"gs-ytube--link\"> Thony y Thor se van a las manos \ud83e\udd4a |... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfAlguna vez te preguntaste qu\u00e9 pas\u00f3 realmente entre Thony y Thor en Avengers: La Era de Ultr\u00f3n? Olvidate de las gemas del infinito, la inteligencia artificial y salvar al mundo. La verdadera raz\u00f3n de esta pelea \u00e9pica es mucho, MUCHO...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            3 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            69        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_s1aq5QGd-j0_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/s1aq5QGd-j0\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_5DzA21Cskec_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/5DzA21Cskec\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Robert Downey Jr. y el DESASTRE de las sillas vac\u00edas \ud83e\udd26\u200d\u2642\ufe0f\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:28    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_5DzA21Cskec_2\" class=\"gs-ytube--link\"> Robert Downey Jr. y el DESASTRE de las sillas vac\u00edas... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >Se filtraron las verdaderas cintas del anuncio de Avengers: Doomsday. \ud83d\ude31 Descubre por qu\u00e9 a Robert Downey Jr. le cost\u00f3 tanto grabar la ic\u00f3nica escena de Doctor Doom frente a las sillas de los Vengadores. \u00a1Un detr\u00e1s de c\u00e1maras lleno...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            42 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            1K        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_5DzA21Cskec_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/5DzA21Cskec\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_sh0w4dWtinw_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/sh0w4dWtinw\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"\u00bfQu\u00e9 pasa en el Show de Truman?\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:36    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_sh0w4dWtinw_2\" class=\"gs-ytube--link\"> \u00bfQu\u00e9 pasa en el Show de Truman? <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >En esta parodia de la ic\u00f3nica escena del auto, Truman (Jim Carrey) comienza a sospechar que algo no va bien cuando ve por el retrovisor un bucle imposible: \u00a1dos Dinosaurios, el Titanic y Donald Trump pasando una y otra vez!\n\nPero...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            37 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            1K        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_sh0w4dWtinw_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/sh0w4dWtinw\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_JreFbHJmiCE_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/JreFbHJmiCE\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"la Matrix se vuelve peronista \u270c\ufe0f\ud83d\udc8a\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:46    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_JreFbHJmiCE_2\" class=\"gs-ytube--link\"> la Matrix se vuelve peronista \u270c\ufe0f\ud83d\udc8a <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfY si Morfeo no fuera quien gu\u00eda a Neo? En una realidad alternativa, la terminal de Thomas Anderson recibe una llamada filtrada que cambia el destino de la humanidad (o al menos del Instituto Patria).\nEl crossover definitivo entre el cine...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            46 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            1K        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_JreFbHJmiCE_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/JreFbHJmiCE\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_F5PoccKVw24_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/F5PoccKVw24\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Tr\u00e1iler2: Avengers DOOMSDAY #avengersdoomsday  #robertdowneyjr  #marvel  #avengers   #doctordoom\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:46    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_F5PoccKVw24_2\" class=\"gs-ytube--link\"> Tr\u00e1iler2: Avengers DOOMSDAY #avengersdoomsday  #robertdowneyjr  #marvel  #avengers... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00a1Siguen apareciendo nuevos personajes en Avengers Doomsday!\n\n#elcanaldelwason #parodias #humorabsurdo #doblajesgraciosos #videosgraciosos  \n#culturapop #comics #videosretro #humornostalgico  \n#animacion2d #wasoverso #videosconia #terminatorparodia #parodiasmarvel #videojuegosretro #ochentasynoventas #uruguaycreativo #humorlatino  #wasohumor<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            47 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            1K        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            1\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_F5PoccKVw24_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/F5PoccKVw24\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_T5lgHZPwK9w_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/T5lgHZPwK9w\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Nuevo Tr\u00e1iler: Avengers DOOMSDAY#AvengersDoomsday #RobertDowneyJr #Marvel #avengers  #doctordoom\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:41    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_T5lgHZPwK9w_2\" class=\"gs-ytube--link\"> Nuevo Tr\u00e1iler: Avengers DOOMSDAY#AvengersDoomsday #RobertDowneyJr #Marvel #avengers  #doctordoom <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >Nuevos personaje se suman a Avengers Doomsday\n#avengers #avengersdoomsday #humorabsurdo #marvel<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            31 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            1K        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            4\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_T5lgHZPwK9w_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/T5lgHZPwK9w\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_Efkd1fu6eW0_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/Efkd1fu6eW0\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Cumbres Borrascosas: El tr\u00e1iler que NO quieren que veas (Cumbre Babosas)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:14    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_Efkd1fu6eW0_2\" class=\"gs-ytube--link\"> Cumbres Borrascosas: El tr\u00e1iler que NO quieren que veas (Cumbre... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfPensabas que la nueva pel\u00edcula de Cumbres Borrascosas iba a ser un drama rom\u00e1ntico normal? Te presento &quot;Cumbre Babosas&quot;.\nEn este tr\u00e1iler editado con el poder (y la falta de sentido com\u00fan) de la Inteligencia Artificial, las cosas se salen de...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            6 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            502        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_Efkd1fu6eW0_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/Efkd1fu6eW0\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_2z-Wz-PgdFA_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/2z-Wz-PgdFA\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Nuevo Tr\u00e1iler de HE-MAN: Escenas In\u00e9ditas  y un Final Inesperado\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:54    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_2z-Wz-PgdFA_2\" class=\"gs-ytube--link\"> Nuevo Tr\u00e1iler de HE-MAN: Escenas In\u00e9ditas  y un Final... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >Nuevo Tr\u00e1iler de la pel\u00edcula de He-Man \nPero eso no es todo... \u00a1qu\u00e9dense hasta el final! Porque hasta el villano m\u00e1s temido tiene su lado art\u00edstico. Cerramos este tr\u00e1iler con un musical exclusivo de Skeletor que te dejar\u00e1 sin palabras....<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            4 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            166        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_2z-Wz-PgdFA_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/2z-Wz-PgdFA\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_cM8Z7M1ms7g_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/cM8Z7M1ms7g\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Cumbres Borrascosas: El tr\u00e1iler de Cumbre Babosas\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:13    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_cM8Z7M1ms7g_2\" class=\"gs-ytube--link\"> Cumbres Borrascosas: El tr\u00e1iler de Cumbre Babosas <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfPensabas que la nueva pel\u00edcula de Cumbres Borrascosas iba a ser un drama rom\u00e1ntico normal? Te presento &quot;Cumbre Babosas&quot;.\nEn este tr\u00e1iler editado con el poder (y la falta de sentido com\u00fan) de la Inteligencia Artificial, las cosas se salen de...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            10 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            176        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_cM8Z7M1ms7g_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/cM8Z7M1ms7g\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_sj2mqD0I9qU_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/sj2mqD0I9qU\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"R\u00c1PIDO Y GILAZOS \ud83d\ude02\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:32    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_sj2mqD0I9qU_2\" class=\"gs-ytube--link\"> R\u00c1PIDO Y GILAZOS \ud83d\ude02 <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >&quot;Rubio Paul Waker&quot; y a Toretto (en su versi\u00f3n m\u00e1s gil) en la carrera que lo empez\u00f3 todo. Prep\u00e1rate para chistes absurdos, derrapes sin sentido y una canci\u00f3n parodia que te har\u00e1 preguntarte por qu\u00e9 sigues viendo esto.\n\n\u00a1Esto no es...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            4 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            516        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_sj2mqD0I9qU_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/sj2mqD0I9qU\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_NDzpqISpXn8_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/NDzpqISpXn8\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"R\u00c1PIDO Y GILAZOS \ud83d\ude02 (Parodia R\u00e1pido y Furioso)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:32    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_NDzpqISpXn8_2\" class=\"gs-ytube--link\"> R\u00c1PIDO Y GILAZOS \ud83d\ude02 (Parodia R\u00e1pido y Furioso) <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfCre\u00edas que la primera carrera de R\u00e1pido y Furioso era intensa? Es porque no hab\u00edas visto &quot;R\u00c1PIDO Y GILAZOS&quot;.\n\nAcompa\u00f1a al &quot;Rubio Paul Waker&quot; y a Toretto (en su versi\u00f3n m\u00e1s gil) en la carrera que lo empez\u00f3 todo. Prep\u00e1rate para...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            7 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            87        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_NDzpqISpXn8_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/NDzpqISpXn8\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_UKEKsaqeM74_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/UKEKsaqeM74\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Johnny Cage vs Scorpion: La Batalla de Baile #mortalkombat1  #johnnycage #scorpion  #dancebattle\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:18    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_UKEKsaqeM74_2\" class=\"gs-ytube--link\"> Johnny Cage vs Scorpion: La Batalla de Baile #mortalkombat1 ... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >El verdadero duelo es en la pista de baile. Johnny Cage y Scorpion se enfrentan con sus mejores pasos en este musical improvisado.\n\n#shorts #mortalkombat #johnnycage #scorpion #dancebattle<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            11 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            916        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_UKEKsaqeM74_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/UKEKsaqeM74\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_axHqOY4U6aQ_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/axHqOY4U6aQ\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"La Verdadera (y Confusa) Familia de Darth Vader\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:45    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_axHqOY4U6aQ_2\" class=\"gs-ytube--link\"> La Verdadera (y Confusa) Familia de Darth Vader <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfCre\u00edas que la familia Skywalker era complicada? \u00a1No has visto nada! \ud83e\udd2f\nTodos conocemos la m\u00edtica escena donde Darth Vader le dice a Luke: &quot;Yo soy tu padre&quot;. Pero en nuestra versi\u00f3n... las cosas son un poquito diferentes.\nPrep\u00e1rate para una revelaci\u00f3n...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            10 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            95        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            1\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_axHqOY4U6aQ_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/axHqOY4U6aQ\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_YvNGCzxMyjQ_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/YvNGCzxMyjQ\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"\u00a1Todos levantan el martillo de Thor... MENOS THOR! (Parodia Avengers)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:26    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_YvNGCzxMyjQ_2\" class=\"gs-ytube--link\"> \u00a1Todos levantan el martillo de Thor... MENOS THOR! (Parodia Avengers) <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfRecuerdas la famosa escena de &quot;Avengers: Era de Ultr\u00f3n&quot; donde todos intentan levantar el martillo de Thor?\nBueno, en esta parodia, las cosas son UN POCO diferentes.\n\u00bfQu\u00e9 pasar\u00eda si el Capit\u00e1n Am\u00e9rica, Iron Man, Hulk y hasta Black Widow pudieran levantar...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            419 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            6K        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            22\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_YvNGCzxMyjQ_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/YvNGCzxMyjQ\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_z01TMRLk5Jk_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/z01TMRLk5Jk\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Wolverine vs Magneto: Una historia de amor (y vigas)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:33    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_z01TMRLk5Jk_2\" class=\"gs-ytube--link\"> Wolverine vs Magneto: Una historia de amor (y vigas) <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >Wolverine y Magneto .. inesperado? \ud83d\ude33\n\nMagneto usa sus poderes de formas creativas y Wolverine descubre un nuevo sentimiento.\n\nEste short es una parodia de X-Men y un homenaje al gran estilo del canal &#039;The Top Comics&#039;. \u00a1Todo con humor!\n\n#shorts #wolverine #magneto...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            57 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            1K        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            2\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_z01TMRLk5Jk_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/z01TMRLk5Jk\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_i0q5tie7NQs_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/i0q5tie7NQs\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"El Exorcista de las Flatulencias\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:40    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_i0q5tie7NQs_2\" class=\"gs-ytube--link\"> El Exorcista de las Flatulencias <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfQu\u00e9 pasa si la escena m\u00e1s aterradora de &#039;El Exorcista&#039; se mezcla con... un problema g\u00e1strico? \ud83d\udca8\n\u00a1Bienvenido a &#039;El Exorcista de las Flatulencias&#039;!\nPreparamos una parodia de la ic\u00f3nica escena donde los dos sacerdotes entran al cuarto de la ni\u00f1a pose\u00edda....<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            7 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            41        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_i0q5tie7NQs_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/i0q5tie7NQs\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_ATQHDDg8Dt4_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/ATQHDDg8Dt4\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"\u00a1No solo Will Smith! TODOS los que golpearon a Chris Rock \ud83d\udc7d\ud83d\udc19\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:01    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_ATQHDDg8Dt4_2\" class=\"gs-ytube--link\"> \u00a1No solo Will Smith! TODOS los que golpearon a Chris... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >Bienvenidos a El Canal del Wason, donde los c\u00f3mics, los videojuegos retro y el humor absurdo se fusionan para traerte videos \u00fanicos.\nParodias, doblajes, edits locos con inteligencia artificial, historias bizarras, y personajes que te van a hacer re\u00edr... o llorar...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            10 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            555        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_ATQHDDg8Dt4_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/ATQHDDg8Dt4\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_nDiUi__bBn4_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/nDiUi__bBn4\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Brad Pitt es NOQUEADO por una X-Men (Parodia Joe Black)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:03    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_nDiUi__bBn4_2\" class=\"gs-ytube--link\"> Brad Pitt es NOQUEADO por una X-Men (Parodia Joe Black) <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00a1Todos recordamos la ic\u00f3nica escena donde Susan conoce a Joe Black en la cafeter\u00eda! Esa qu\u00edmica, esa tensi\u00f3n... \u00bfPero qu\u00e9 hubiera pasado si todo fuera terriblemente absurdo?\nEn nuestra versi\u00f3n, la conversaci\u00f3n da un giro inesperado. Cuando las cosas se salen...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            6 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            552        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            1\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_nDiUi__bBn4_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/nDiUi__bBn4\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_sbuoKjL3tXc_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/sbuoKjL3tXc\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"\u00bfQu\u00e9 pasa en el Show de Truman? (Parodia con Dinosaurios y el Titanic)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:45    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_sbuoKjL3tXc_2\" class=\"gs-ytube--link\"> \u00bfQu\u00e9 pasa en el Show de Truman? (Parodia con Dinosaurios... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >En esta parodia de la ic\u00f3nica escena del auto, Truman (Jim Carrey) comienza a sospechar que algo no va bien cuando ve por el retrovisor un bucle imposible: \u00a1dos Dinosaurios, el Titanic y Donald Trump pasando una y otra vez!\n\nPero...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            9 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            122        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_sbuoKjL3tXc_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/sbuoKjL3tXc\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_ppao7JWPFeQ_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/ppao7JWPFeQ\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"&quot;Veo cosas... peores que gente muerta&quot; (Parodia Sexto Sentido)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:36    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_ppao7JWPFeQ_2\" class=\"gs-ytube--link\"> &quot;Veo cosas... peores que gente muerta&quot; (Parodia Sexto Sentido) <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfRecuerdas la famosa escena de &quot;Sexto Sentido&quot;? La hemos tra\u00eddo al siglo XXI, y es mucho m\u00e1s aterradora.\nEn esta parodia de la ic\u00f3nica pel\u00edcula, el peque\u00f1o Cole tiene una confesi\u00f3n que hiela la sangre. \u00c9l no ve fantasmas... ve cosas...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            7 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            480        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_ppao7JWPFeQ_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/ppao7JWPFeQ\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_vloFwTNIjzM_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/vloFwTNIjzM\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Ellie Sattler ROBA el Protagonismo (Y el Dino se Descontrola) | Parodia Jurassic Park\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:53    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_vloFwTNIjzM_2\" class=\"gs-ytube--link\"> Ellie Sattler ROBA el Protagonismo (Y el Dino se Descontrola)... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfRecuerdas ese momento \u00e9pico y m\u00e1gico cuando el Dr. Grant y la Dra. Sattler ven por primera vez a los dinosaurios? Bueno, en nuestra versi\u00f3n, ese momento m\u00e1gico se vuelve... bastante asqueroso. \ud83d\udca9\nAcompa\u00f1a a Alan Grant y Ellie Sattler en...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            29 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            4K        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            1\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_vloFwTNIjzM_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/vloFwTNIjzM\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_8rHvHubc98U_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/8rHvHubc98U\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Home Alone: Psycho - La Venganza de Kevin (Versi\u00f3n Dram\u00e1tica)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:15    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_8rHvHubc98U_2\" class=\"gs-ytube--link\"> Home Alone: Psycho - La Venganza de Kevin (Versi\u00f3n Dram\u00e1tica) <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >Prep\u00e1rate para ver &#039;Solo en Casa&#039; como nunca antes. En esta escalofriante reinterpretaci\u00f3n de la cl\u00e1sica historia, Kevin McCallister no solo se defiende, sino que se convierte en una fuerza imparable cuando dos ladrones intentan invadir su hogar. \u00bfQu\u00e9 sucede...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            14 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            577        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_8rHvHubc98U_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/8rHvHubc98U\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_vcLnptG_PpU_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/vcLnptG_PpU\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"El Duelo M\u00c1S RARO del Lejano Oeste (Parodia Western)\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        2:33    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_vcLnptG_PpU_2\" class=\"gs-ytube--link\"> El Duelo M\u00c1S RARO del Lejano Oeste (Parodia Western) <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfCre\u00edas que hab\u00edas visto todos los duelos del lejano oeste? Pi\u00e9nsalo de nuevo.\nEn esta parodia de la escena final del cl\u00e1sico western &quot;La Venganza Definitiva&quot;, nuestro h\u00e9roe se prepara para el duelo final. Pero algo... no est\u00e1 bien.\nPrep\u00e1rate para un...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            11 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            105        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            1\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_vcLnptG_PpU_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/vcLnptG_PpU\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_dbRb57jPUjI_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/dbRb57jPUjI\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Ghost: \u00a1Masivo!\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:17    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_dbRb57jPUjI_2\" class=\"gs-ytube--link\"> Ghost: \u00a1Masivo! <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >Mat\u00edas El Colorado y Llados recreando una escena  cl\u00e1sica del cine..\n\n#humornostalgico   \n #parodias #youtuber  #llados  #lladosfitness  #humorlatino  #colorado<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            5 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            37        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_dbRb57jPUjI_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/dbRb57jPUjI\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_Hj9geuz0fpg_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/Hj9geuz0fpg\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"\u00a1Alfred se EMPUTECE!\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:00    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_Hj9geuz0fpg_2\" class=\"gs-ytube--link\"> \u00a1Alfred se EMPUTECE! <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >Alfred no pudo controlar la rabia y la humillaci\u00f3n... \u00a1y la reacci\u00f3n de Bruno D\u00edaz es ORO puro! \ud83e\udd23 Un Short con una declaraci\u00f3n de amor, un enfado \u00e9pico y el final m\u00e1s inesperado. \u00a1Dale like si te re\u00edste!\n\n\ud83d\udd14 Suscr\u00edbete...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            5 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            146        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_Hj9geuz0fpg_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/Hj9geuz0fpg\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_4Svunl-TltI_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/4Svunl-TltI\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Wolverine versi\u00f3n LATAM: Con esponja de aluminio duele m\u00e1s. #Wolverine #Parodia  #EmilioGarras\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:26    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_4Svunl-TltI_2\" class=\"gs-ytube--link\"> Wolverine versi\u00f3n LATAM: Con esponja de aluminio duele m\u00e1s. #Wolverine... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfAdamantium? \u00a1Eso es para millonarios! En esta versi\u00f3n del origen de Wolverine, a nuestro querido Emilio Garras le hacemos la mejora con tecnolog\u00eda de punta y presupuesto local: una esponja de aluminio y mucha mala suerte.\nUna parodia animada con canci\u00f3n...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            7 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            72        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_4Svunl-TltI_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/4Svunl-TltI\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_flbdsydfYYQ_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/flbdsydfYYQ\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Hulk vs Natasha: \u00a1No me des un GRR! \ud83d\udca5#Hulk #Natasha #Avengers #Reggaeton #DameUnGrr #Shorts #Marvel\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:31    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_flbdsydfYYQ_2\" class=\"gs-ytube--link\"> Hulk vs Natasha: \u00a1No me des un GRR! \ud83d\udca5#Hulk #Natasha... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >Cuando Hulk persigue a Natasha\u2026 todo se vuelve un reggaet\u00f3n \ud83d\udd25\nParodia divertida mezclando la ic\u00f3nica escena de Avengers con el hit del momento &quot;Dame un GRR&quot;. \u00a1Prep\u00e1rate para re\u00edr y bailar! \ud83d\ude06\ud83d\udc83\ud83d\udfe2<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            10 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            321        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_flbdsydfYYQ_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/flbdsydfYYQ\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_ryVv2eyRa-8_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/ryVv2eyRa-8\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Spider-Man 2\u2026 \u00a1pero Mary Jane pide sinceridad brutal! #SpiderMan  #Shorts #MaryJane  #FunnyShort\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:49    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_ryVv2eyRa-8_2\" class=\"gs-ytube--link\"> Spider-Man 2\u2026 \u00a1pero Mary Jane pide sinceridad brutal! #SpiderMan ... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfY si Peter Parker no fuera tan rom\u00e1ntico? \ud83d\udd77\ufe0f\ud83d\udc94 En esta parodia absurda de Spider-Man 2, Mary Jane corta de ra\u00edz el momento meloso y exige la verdad sin vueltas.\n\nUn short cargado de humor rid\u00edculo y cero romanticismo.\nSi te sac\u00f3...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            7 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            46        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_ryVv2eyRa-8_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/ryVv2eyRa-8\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_JG0-vyvgx5w_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/JG0-vyvgx5w\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"The Truman Show\u2026 \u00a1pero con condones! #TheTrumanShow  #Shorts #Condones #Comedia #Cine #Rid\u00edculo\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:54    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_JG0-vyvgx5w_2\" class=\"gs-ytube--link\"> The Truman Show\u2026 \u00a1pero con condones! #TheTrumanShow  #Shorts #Condones... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >Cuando Truman descubre algo m\u00e1s que la verdad\u2026 descubre los condones del show. \ud83e\udd2f Una parodia absurda inspirada en la ic\u00f3nica escena de la biblioteca de The Truman Show. \u00a1Advertencia! Humor rid\u00edculo y surrealista garantizado.\n\nSi te gust\u00f3, no olvides darle...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            41 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            1K        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_JG0-vyvgx5w_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/JG0-vyvgx5w\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_xNa1ACgZtNE_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/xNa1ACgZtNE\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"\ud83d\udc49 El Chasquido de Thanos Remix \ud83d\udca5 #Avengers #Thanos #MarvelParody #Shorts #ElectroRemix #TonyStark\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:08    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_xNa1ACgZtNE_2\" class=\"gs-ytube--link\"> \ud83d\udc49 El Chasquido de Thanos Remix \ud83d\udca5 #Avengers #Thanos #MarvelParody... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfQu\u00e9 pasar\u00eda si en lugar de borrar medio universo\u2026 Thanos hubiera iniciado la fiesta m\u00e1s \u00e9pica del multiverso? \ud83d\udc83\ud83d\udd7a\nEn este short te traemos \u201cEl Chasquido de Thanos Remix\u201d, un musical electr\u00f3nico donde Tony Stark, Capit\u00e1n Marvel, Hulk, Spider-Man, Doctor Strange...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            52 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            1K        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            1\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_xNa1ACgZtNE_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/xNa1ACgZtNE\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_T5VYln3REh0_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/T5VYln3REh0\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"\ud83d\udea2 Titanic vs Aliens \ud83d\udc7d\ud83d\udca5 | El final que nunca viste #Titanic #Aliens #Parodia #Shorts #SciFi #Humor\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:11    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_T5VYln3REh0_2\" class=\"gs-ytube--link\"> \ud83d\udea2 Titanic vs Aliens \ud83d\udc7d\ud83d\udca5 | El final que nunca... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfQu\u00e9 hubiera pasado si en la famosa escena del Titanic aparec\u00edan naves espaciales y destru\u00edan el barco? \ud83d\ude80\ud83d\udd25\nUn mashup absurdo y divertido que mezcla la pel\u00edcula cl\u00e1sica con un ataque alien\u00edgena inesperado.\nSi te gust\u00f3, no olvides dejar tu like \ud83d\udc4d...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            9 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            57        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_T5VYln3REh0_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/T5VYln3REh0\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_oJRQjdaXtkM_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/oJRQjdaXtkM\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"&quot;Spider-Man vs la pelea m\u00e1s absurda de su vida \ud83d\udd77\ufe0f&quot; #SpiderMan #Parodia #Shorts #Humor #Cine #Marvel\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:58    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_oJRQjdaXtkM_2\" class=\"gs-ytube--link\"> &quot;Spider-Man vs la pelea m\u00e1s absurda de su vida \ud83d\udd77\ufe0f&quot;... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfQu\u00e9 pasar\u00eda si la primera pelea de Spider-Man en la jaula hubiera sido totalmente absurda?\nEn este short recreamos la ic\u00f3nica escena de la primera pel\u00edcula, pero llevada al extremo del humor:\nPianos cayendo \ud83c\udfb9\nPopcorn interminable \ud83c\udf7f\nUna abuelita Rambo con sart\u00e9n \ud83c\udf73\nOjos...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            10 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            67        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_oJRQjdaXtkM_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/oJRQjdaXtkM\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_ib1G57t_Sqw_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/ib1G57t_Sqw\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"\ud83d\udc49 \u201cRoboCop sin casco\u2026 \u00a1y sin pistola! \ud83e\udd16\ud83d\ude02 | Parodia absurda\u201d #RoboCop #Shorts #Parodia\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:07    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_ib1G57t_Sqw_2\" class=\"gs-ytube--link\"> \ud83d\udc49 \u201cRoboCop sin casco\u2026 \u00a1y sin pistola! \ud83e\udd16\ud83d\ude02 | Parodia... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >\u00bfQu\u00e9 pasar\u00eda si en RoboCop 1 la escena donde se quita el casco fuera un poco m\u00e1s\u2026 rid\u00edcula?\nEn esta parodia absurda, el casco le explota en la cara, Lois no aguanta la risa y RoboCop termina confesando su mayor tristeza:...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            23 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            854        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_ib1G57t_Sqw_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/ib1G57t_Sqw\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_legP0JEQ6R8_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/legP0JEQ6R8\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Daniel San, se la come: \u00bfpara que sirve eso? \ud83e\udd14\ud83e\udd4b | Karate Kid 2 #karatekid2  #DanielSan #Parodia\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:29    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_legP0JEQ6R8_2\" class=\"gs-ytube--link\"> Daniel San, se la come: \u00bfpara que sirve eso? \ud83e\udd14\ud83e\udd4b... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >En esta parodia de Karate Kid II, Daniel San tiene un momento inc\u00f3modo cuando la chica le dice que el Sr. Miyagi est\u00e1 decepcionado de \u00e9l \ud83d\ude31.\nDaniel, confundido, insiste en que quiz\u00e1s quiso decir orgulloso, pero la respuesta no es...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            17 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            535        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_legP0JEQ6R8_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/legP0JEQ6R8\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_ec6ej-zY8kY_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/ec6ej-zY8kY\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Daniel San confundido: \u00bfOrgulloso o decepcionado? \ud83e\udd14\ud83e\udd4b | Karate Kid 2 #karatekid2  #DanielSan #Parodia\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:43    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_ec6ej-zY8kY_2\" class=\"gs-ytube--link\"> Daniel San confundido: \u00bfOrgulloso o decepcionado? \ud83e\udd14\ud83e\udd4b | Karate Kid... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >En esta parodia de Karate Kid II, Daniel San tiene un momento inc\u00f3modo cuando la chica le dice que el Sr. Miyagi est\u00e1 decepcionado de \u00e9l \ud83d\ude31.\nDaniel, confundido, insiste en que quiz\u00e1s quiso decir orgulloso, pero la respuesta no es...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            14 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            120        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_ec6ej-zY8kY_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/ec6ej-zY8kY\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_aX4Xcs6KVSk_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/aX4Xcs6KVSk\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Spider-Man 3 Parodia: Peter y Harry en una charla absurda #spiderman #spiderman3 #tobeymaguire\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:50    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_aX4Xcs6KVSk_2\" class=\"gs-ytube--link\"> Spider-Man 3 Parodia: Peter y Harry en una charla absurda... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >En esta parodia de Spider-Man 3, Peter Parker va al apartamento de Harry Osborn para exigirle que le diga qu\u00e9 pas\u00f3 con Mary Jane.\nPero en vez de un momento tenso\u2026 las cosas se salen de control y terminan en situaciones...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            37 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            1K        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_aX4Xcs6KVSk_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/aX4Xcs6KVSk\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup_GCYsFGw6d3s_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/GCYsFGw6d3s\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Neo intenta doblar la cuchara... y fracasa \ud83e\udd23 | Parodia Matrix\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        1:47    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup_GCYsFGw6d3s_2\" class=\"gs-ytube--link\"> Neo intenta doblar la cuchara... y fracasa \ud83e\udd23 | Parodia... <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >En Matrix, el ni\u00f1o pelado ense\u00f1a a Neo que \u201cno existe la cuchara\u201d...\nPero en esta parodia, Neo simplemente no logra doblarla, \u00a1por m\u00e1s que lo intente! \ud83d\ude02\nUn cl\u00e1sico momento \u00e9pico convertido en humor absurdo.\n\nSi te gust\u00f3, no olvides dejar tu...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            27 <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            900        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            0\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup_GCYsFGw6d3s_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/GCYsFGw6d3s\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n            <div class=\"gs-col-lg-6 gs-col-md-4 gs-col-sm-6 gs-col-xs-12 gs-ytube--single-item\">\n\n                <div class=\"gs-ytube--area_left\">\n\n                    <!-- Video Thumbnail -->\n                    \n<a href=\"#gs_ytgal_popup__67S3U2QR1E_2\" class=\"gs-ytube--link\">\n\n    <!-- Video thumbnail -->\n    <div class=\"gs-ytube--thumbnail\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i.ytimg.com\/vi\/_67S3U2QR1E\/hqdefault.jpg\" width=\"480\" height=\"360\" alt=\"Terminator pide combo\">    <\/div>\n\n    <div class=\"gs-ytube--overlay\"><\/div>\n\n    <!-- Play Icon -->\n    <span class=\"gs-ytube--icon\">\n\n        \n            <!-- Generator: Adobe Illustrator 26.2.1, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n            <svg version=\"1.1\" id=\"Layer_1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\n                viewBox=\"0 0 60 42\" style=\"enable-background:new 0 0 60 42;\" xml:space=\"preserve\">\n                <style type=\"text\/css\">\n                    .st0{fill-rule:evenodd;clip-rule:evenodd;}\n                <\/style>\n                <path class=\"st0\" d=\"M58.8,6.9c0-0.1-0.1-0.2-0.1-0.3c0,0,0,0,0,0c0,0,0,0,0-0.1l0,0.1c0,0,0,0,0-0.1c0,0,0,0,0,0\n                    c0-0.1-0.1-0.2-0.1-0.3c-0.4-1.1-1-2.1-1.8-3c-0.9-0.9-2.1-1.6-3.4-1.9C48.8,0,30,0,30,0S11.2,0,6.6,1.3c-1.3,0.3-2.4,1-3.4,1.9\n                    C2.3,4.1,1.6,5.3,1.3,6.6C0,11.2,0,21,0,21s0,9.8,1.3,14.5c0.3,1.3,1,2.4,1.9,3.4c0.9,0.9,2.1,1.6,3.4,1.9C11.2,42,30,42,30,42\n                    s18.8,0,23.4-1.3c1.3-0.3,2.4-1,3.4-1.9c0.9-0.9,1.6-2.1,1.9-3.4C60,30.8,60,21,60,21S60,11.7,58.8,6.9z M58,21L58,21l0,0.1\n                    c0,0.1,0,0.2,0,0.3c0,0.3,0,0.7,0,1.2c0,1-0.1,2.3-0.1,3.8c-0.2,3-0.5,6.5-1,8.6l0,0c-0.2,0.9-0.7,1.8-1.4,2.5\n                    c-0.7,0.7-1.5,1.2-2.5,1.4c-1,0.3-2.8,0.5-5.3,0.7c-2.4,0.2-5.1,0.3-7.8,0.4C37.3,39.9,34.8,40,33,40c-0.9,0-1.7,0-2.2,0\n                    c-0.3,0-0.5,0-0.6,0L30,40l-0.2,0c-0.1,0-0.3,0-0.6,0c-0.5,0-1.3,0-2.2,0c-1.8,0-4.3-0.1-6.9-0.1c-2.6-0.1-5.4-0.2-7.7-0.4\n                    c-2.4-0.2-4.3-0.4-5.3-0.6c-0.9-0.3-1.8-0.7-2.5-1.4c-0.7-0.7-1.2-1.5-1.4-2.5c-0.6-2.1-0.9-5.6-1-8.6C2.1,24.9,2,23.5,2,22.6\n                    c0-0.5,0-0.9,0-1.1c0-0.1,0-0.2,0-0.3L2,21v0l0-0.1c0-0.1,0-0.2,0-0.3c0-0.3,0-0.7,0-1.1c0-1,0.1-2.3,0.1-3.8c0.2-3,0.5-6.4,1-8.6\n                    l0,0c0.2-0.9,0.7-1.8,1.4-2.5c0.7-0.7,1.5-1.2,2.5-1.4c1-0.3,2.8-0.5,5.3-0.7c2.4-0.2,5.1-0.3,7.7-0.4C22.7,2.1,25.2,2,27,2\n                    c0.9,0,1.7,0,2.2,0c0.3,0,0.5,0,0.6,0L30,2l0.2,0c0.1,0,0.3,0,0.6,0c0.5,0,1.3,0,2.2,0c1.8,0,4.3,0.1,6.9,0.1\n                    c2.6,0.1,5.4,0.2,7.8,0.4C50.1,2.7,52,2.9,53,3.2c0.9,0.3,1.8,0.7,2.5,1.4c0.7,0.7,1.2,1.5,1.4,2.4l0,0c0.6,2.1,0.9,5.5,1,8.6\n                    c0.1,1.5,0.1,2.8,0.1,3.8c0,0.5,0,0.9,0,1.1c0,0.1,0,0.2,0,0.3L58,21L58,21z\"\/>\n                <path d=\"M23.8,12v18l16-9L23.8,12z\"\/>\n            <\/svg>\n\n        \n    <\/span>\n\n\n    <!-- Video Duration -->\n    <span class=\"gs-ytube--duration\">\n        0:16    <\/span>\n\n<\/a>\n\n                <\/div>\n\n                <div class=\"gs-ytube--area_right\">\n\n                    <div class=\"gs-ytube--area_right-top gs-ytube--scrollbar\">\n\n                        <!-- Video Title -->\n                        \n<h3 class=\"gs-ytube-title\">\n    <a href=\"#gs_ytgal_popup__67S3U2QR1E_2\" class=\"gs-ytube--link\"> Terminator pide combo <\/a>\n<\/h3>\n\n                        <!-- Video Description -->\n                        \n<p class=\"gs-ytube-vid-desc\" >Bienvenidos a El Canal del Wason, donde los c\u00f3mics, los videojuegos retro y el humor absurdo se fusionan para traerte videos \u00fanicos.\nParodias, doblajes, edits locos con inteligencia artificial, historias bizarras, y personajes que te van a hacer re\u00edr... o llorar...<\/p>\n\n                    <\/div>\n                    \n                    <!-- Video Information -->\n                    \n<div class=\"gs-ytube-v-info-wrapper\">\n\n    <p class=\"gs-ytube-v-info\">\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-like-count\">\n\n            <svg width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M12.9521 4.86619H10.1561L10.7045 3.1748C10.8748 2.6469 10.8717 2.07637 10.6957 1.55045C10.5197 1.02453 10.1806 0.572179 9.73011 0.262584C9.39292 0.0352028 8.98277 -0.0490299 8.58617 0.027651C8.18957 0.104332 7.83751 0.335932 7.60426 0.673605L4.61932 5.04479C4.5013 4.9298 4.34462 4.86584 4.18182 4.86619H0.636364C0.467589 4.86619 0.305728 4.93492 0.186387 5.05728C0.0670453 5.17963 0 5.34557 0 5.5186V13.3476C0 13.5206 0.0670453 13.6866 0.186387 13.8089C0.305728 13.9313 0.467589 14 0.636364 14H4.18182C4.35059 14 4.51245 13.9313 4.63179 13.8089C4.75114 13.6866 4.81818 13.5206 4.81818 13.3476V13.2611L5.73773 13.8903C5.84242 13.9616 5.96524 13.9997 6.09091 14H11.8182C11.9364 14 12.0524 13.9663 12.153 13.9026C12.2536 13.8388 12.3349 13.7476 12.3877 13.6391L14.7156 8.86508C14.902 8.48123 14.9994 8.05838 15 7.62957V6.96533C14.9993 6.40877 14.7833 5.87522 14.3993 5.4817C14.0154 5.08819 13.495 4.86683 12.9521 4.86619ZM3.54545 12.6952H1.27273V6.17102H3.54545V12.6952ZM13.7273 7.62957C13.7269 7.85602 13.6755 8.07932 13.5769 8.28199L11.4248 12.6952H6.28182L4.81818 11.6937V7.02894L8.6471 1.42144C8.68807 1.36091 8.75058 1.3193 8.82118 1.30557C8.89178 1.29185 8.96481 1.3071 9.02455 1.34804C9.24339 1.49837 9.40816 1.71809 9.49364 1.97355C9.57912 2.22901 9.58059 2.50615 9.49784 2.76256L8.67057 5.31228C8.63872 5.41022 8.63 5.51452 8.64512 5.61659C8.66025 5.71866 8.69879 5.8156 8.75757 5.89943C8.81635 5.98326 8.8937 6.05159 8.98326 6.0988C9.07281 6.14602 9.17202 6.17077 9.27273 6.17102H12.9521C13.1576 6.17113 13.3546 6.25483 13.5 6.40376C13.6453 6.55269 13.7271 6.75466 13.7273 6.96533V7.62957Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            1K <span>Likes<\/span>        \n        <\/span>\n\n        <!-- Video View Count -->\n        <span class=\"gs-ytube-view-count\">\n            \n            <svg width=\"18\" height=\"12\" viewBox=\"0 0 18 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.99834 4.07764e-06C7.23308 -0.00157586 5.49834 0.455998 3.9676 1.32697C2.43687 2.19793 1.16378 3.45177 0.275673 4.96308C0.0950765 5.27295 0 5.62446 0 5.98228C0 6.34009 0.0950765 6.6916 0.275673 7.00148C1.15816 8.52019 2.42909 9.78166 3.96044 10.6588C5.49178 11.536 7.22944 11.9978 8.99834 11.9978C10.7672 11.9978 12.5049 11.536 14.0362 10.6588C15.5676 9.78166 16.8385 8.52019 17.721 7.00148C17.9016 6.6916 17.9967 6.34009 17.9967 5.98228C17.9967 5.62446 17.9016 5.27295 17.721 4.96308C16.8308 3.45357 15.5573 2.2012 14.027 1.3305C12.4967 0.459797 10.7631 0.00109478 8.99834 4.07764e-06ZM16.549 6.32792C15.7812 7.63773 14.6796 8.72484 13.3545 9.4805C12.0295 10.2362 10.5273 10.6339 8.99834 10.6339C7.46938 10.6339 5.96722 10.2362 4.64213 9.4805C3.31704 8.72484 2.21548 7.63773 1.44764 6.32792C1.39045 6.22631 1.36043 6.11191 1.36043 5.99557C1.36043 5.87924 1.39045 5.76483 1.44764 5.66322C2.21485 4.35532 3.31521 3.26985 4.63869 2.51534C5.96217 1.76083 7.4624 1.36373 8.98939 1.36373C10.5164 1.36373 12.0166 1.76083 13.3401 2.51534C14.6636 3.26985 15.7639 4.35532 16.5311 5.66322C16.5883 5.76483 16.6184 5.87924 16.6184 5.99557C16.6184 6.11191 16.5883 6.22631 16.5311 6.32792H16.549Z\" fill=\"#191919\"\/>\n                <path d=\"M8.99814 2.65879C8.33461 2.65879 7.68598 2.85371 7.13427 3.2189C6.58257 3.58409 6.15257 4.10315 5.89865 4.71044C5.64472 5.31772 5.57829 5.98597 5.70773 6.63066C5.83718 7.27535 6.1567 7.86754 6.62589 8.33234C7.09508 8.79714 7.69286 9.11367 8.34364 9.24191C8.99442 9.37014 9.66897 9.30433 10.282 9.05278C10.895 8.80123 11.419 8.37525 11.7876 7.82871C12.1563 7.28216 12.353 6.6396 12.353 5.98228C12.353 5.10084 11.9996 4.25549 11.3704 3.63222C10.7412 3.00895 9.88791 2.65879 8.99814 2.65879ZM8.99814 7.97637C8.60002 7.97637 8.21084 7.85942 7.87982 7.64031C7.5488 7.42119 7.2908 7.10976 7.13844 6.74538C6.98609 6.38101 6.94623 5.98007 7.0239 5.59325C7.10157 5.20644 7.29328 4.85112 7.57479 4.57224C7.8563 4.29337 8.21497 4.10345 8.60544 4.0265C8.99591 3.94956 9.40064 3.98905 9.76845 4.13998C10.1363 4.29091 10.4506 4.54649 10.6718 4.87442C10.893 5.20235 11.0111 5.58789 11.0111 5.98228C11.0111 6.51115 10.799 7.01835 10.4215 7.39231C10.044 7.76628 9.532 7.97637 8.99814 7.97637Z\" fill=\"#191919\"\/>\n            <\/svg>\n\n            47K        \n        <\/span>\n\n        <!-- Video Comment Count -->\n        <span class=\"gs-ytube-comment-count\">\n            \n            <svg width=\"17\" height=\"14\" viewBox=\"0 0 17 14\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M8.36719 14C8.19107 14 8.02216 13.933 7.89762 13.8136C7.77309 13.6943 7.70312 13.5324 7.70312 13.3636V12.0909C7.70312 11.9221 7.63316 11.7603 7.50863 11.6409C7.38409 11.5216 7.21518 11.4545 7.03906 11.4545H5.97656C2.68104 11.4545 0 8.88533 0 5.72727C0 2.56921 2.68104 0 5.97656 0H11.0234C14.319 0 17 2.56921 17 5.72727C17 5.75358 17 5.77988 17 5.80576C16.9845 7.3483 16.4953 8.50479 15.4147 9.55479C14.4252 10.5157 12.9798 11.3697 10.9796 12.5521C10.3062 12.95 9.54258 13.4005 8.72401 13.9007C8.61728 13.9655 8.49354 14 8.36719 14ZM5.97656 1.27273C4.74372 1.27273 3.56137 1.74204 2.68962 2.57743C1.81787 3.41282 1.32812 4.54585 1.32812 5.72727C1.32812 6.90869 1.81787 8.04172 2.68962 8.87711C3.56137 9.7125 4.74372 10.1818 5.97656 10.1818H7.03906C7.56724 10.1824 8.07362 10.3837 8.4471 10.7416C8.82059 11.0995 9.03066 11.5848 9.03125 12.0909V12.211C9.47396 11.9462 9.8932 11.6985 10.2823 11.469C12.2037 10.3333 13.5916 9.51279 14.4686 8.66091C15.3097 7.84297 15.659 7.0123 15.6714 5.79345C15.6714 5.77139 15.6714 5.75103 15.6714 5.72727C15.67 4.54634 15.1799 3.41416 14.3085 2.57907C13.4372 1.74399 12.2558 1.27419 11.0234 1.27273H5.97656Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 5.09091H5.97656C5.80044 5.09091 5.63154 5.02386 5.507 4.90452C5.38246 4.78518 5.3125 4.62332 5.3125 4.45455C5.3125 4.28577 5.38246 4.12391 5.507 4.00457C5.63154 3.88523 5.80044 3.81818 5.97656 3.81818H11.0234C11.1996 3.81818 11.3685 3.88523 11.493 4.00457C11.6175 4.12391 11.6875 4.28577 11.6875 4.45455C11.6875 4.62332 11.6175 4.78518 11.493 4.90452C11.3685 5.02386 11.1996 5.09091 11.0234 5.09091Z\" fill=\"black\"\/>\n                <path d=\"M11.0234 7.63636H5.97656C5.80044 7.63636 5.63154 7.56932 5.507 7.44998C5.38246 7.33064 5.3125 7.16877 5.3125 7C5.3125 6.83123 5.38246 6.66936 5.507 6.55002C5.63154 6.43068 5.80044 6.36364 5.97656 6.36364H11.0234C11.1996 6.36364 11.3685 6.43068 11.493 6.55002C11.6175 6.66936 11.6875 6.83123 11.6875 7C11.6875 7.16877 11.6175 7.33064 11.493 7.44998C11.3685 7.56932 11.1996 7.63636 11.0234 7.63636Z\" fill=\"black\"\/>\n            <\/svg>\n            \n            15\n        <\/span>\n\n    <\/p>\n\n<\/div>\n\n                <\/div>\n\n\n                <!-- Popup -->\n                \n<div id=\"gs_ytgal_popup__67S3U2QR1E_2\" class=\"gs_ytgal_popup_shortcode_2 white-popup mfp-hide mfp-with-anim gs_ytgal_popup default\">\n    <div class=\"mfp-content--container\">\n        \n<div class=\"gs-ytgl--iframe\" itemscope=\"\" itemtype=\"http:\/\/schema.org\/Person\">\n\n    <iframe width=\"100%\" src=\"https:\/\/www.youtube.com\/embed\/_67S3U2QR1E\" frameborder=\"0\" allowfullscreen><\/iframe>\n\n<\/div>\n    <\/div>\n<\/div>\n\n            <\/div>\n\n        \n    <\/div>\n<\/div>\n\n\t\t<\/div>\n\n\t\t<style>#gsyt_2 .items .gs-ytgal-name a{font-size:13px !important}#gsyt_2 .items .gs-ytgal-name a{color:rgb(255, 255, 255)!important}#gsyt_2 .items .gs-ytgal-name a{font-weight:normal!important}#gsyt_2 .items .gs-ytgal-name a{font-style:normal!important}<\/style>\n\n\n\n<p class=\"has-text-align-center ext-animate--on\" style=\"margin-top:1.5rem\">Aqu\u00ed no solo vas a encontrar \u00abvideitos para pasar el rato\u00bb. Lo que ves incrustado en esta p\u00e1gina es una selecci\u00f3n curada de lo que pasa por la mente de un payaso que no conoce el significado de la palabra \u00abl\u00edmite\u00bb. Desde parodias que destrozan la l\u00f3gica de tus pel\u00edculas favoritas hasta doblajes que le dan un giro rioplatense a escenas ic\u00f3nicas, este es el rinc\u00f3n donde la locura es la \u00fanica regla. Acomodate, cebate un amargo y preparate, porque pasar de la acci\u00f3n de los juegos a la risa del canal es el c\u00edrculo virtuoso que todo seguidor del Wason debe completar.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity ext-animate--on\"\/>\n\n\n\n<h2 class=\"wp-block-heading ext-animate--on\">\ud83c\udfad \u00bfQu\u00e9 hace \u00fanico al contenido del Wason?<\/h2>\n\n\n\n<p class=\"ext-animate--on\">Hacer re\u00edr en 2026 es un desaf\u00edo t\u00e9cnico y creativo. No se trata solo de poner una cara graciosa frente a la c\u00e1mara; se trata de deconstruir la realidad, usar la s\u00e1tira como herramienta y, sobre todo, mantener una identidad aut\u00e9ntica. En <strong>El Canal del Wason<\/strong>, nuestro contenido se divide en pilares que han formado una comunidad de \u00abviciosos\u00bb leales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading ext-animate--on\">1. Humor Absurdo y Parodias: El Payaso m\u00e1s Bardero<\/h3>\n\n\n\n<p class=\"ext-animate--on\">Nuestras parodias no son simples res\u00famenes. Son cr\u00edticas mordaces disfrazadas de caos. Tomamos esos tropos del cine y la televisi\u00f3n que todos aceptamos como normales y los exponemos bajo la lupa del absurdo. Si alguna vez pensaste que una escena de acci\u00f3n no ten\u00eda sentido, probablemente nosotros ya hicimos un video demostrando por qu\u00e9 es una ridiculez total. Es el lugar donde el payaso sale a \u00abbardear\u00bb con fundamentos, sac\u00e1ndote esa carcajada que no sab\u00edas que necesitabas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading ext-animate--on\">2. Doblajes con \u00abSabor a Mate\u00bb<\/h3>\n\n\n\n<p class=\"ext-animate--on\">El doblaje es un arte, pero el <strong>doblaje del Wason<\/strong> es una experiencia religiosa. Tomamos clips de pel\u00edculas de culto, series de moda o animaciones cl\u00e1sicas y les inyectamos nuestro lenguaje, nuestros modismos y nuestra picard\u00eda rioplatense. No es solo cambiar el idioma; es cambiar la intenci\u00f3n. Ver a un h\u00e9roe de Hollywood hablando como si estuviera esperando el bondi en una esquina de Montevideo o Buenos Aires es lo que nos da esa esencia \u00abUruguay al Palo\u00bb que tanto nos identifica.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity ext-animate--on\"\/>\n\n\n\n<h2 class=\"wp-block-heading ext-animate--on\">\ud83e\uddb8\u200d\u2642\ufe0f Comics y Pel\u00edculas: El \u00abRoast\u00bb que el Multiverso Merece<\/h2>\n\n\n\n<p class=\"ext-animate--on\">Si sos fan\u00e1tico de la cultura geek, sab\u00e9s que a veces las grandes productoras se mandan \u00abmacanas\u00bb monumentales. En esta secci\u00f3n de videos, dedicamos un espacio especial a la informaci\u00f3n de c\u00f3mics y pel\u00edculas, pero con un giro: <strong>la burla sistem\u00e1tica<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list ext-animate--on\">\n<li class=\"ext-animate--on\"><strong>An\u00e1lisis de Poderes:<\/strong> Como viste en nuestro post sobre el [Superman de Christopher Reeve], nos encanta analizar qu\u00e9 tan \u00abrotos\u00bb est\u00e1n los personajes, pero siempre desde un \u00e1ngulo c\u00ednico y divertido.<\/li>\n\n\n\n<li class=\"ext-animate--on\"><strong>Cr\u00edtica de Cine (Sin Filtro):<\/strong> Si una pel\u00edcula tiene un CGI de PS2 o un guion lleno de agujeros, no te vamos a vender humo. Te lo vamos a contar con el humor \u00e1cido que nos caracteriza. Es informaci\u00f3n real disfrazada de entretenimiento absurdo.<\/li>\n\n\n\n<li class=\"ext-animate--on\"><strong>Nostalgia Explosiva:<\/strong> Revisamos esos cl\u00e1sicos que amamos de chicos para darnos cuenta de lo bizarros que eran en realidad.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity ext-animate--on\"\/>\n\n\n\n<h2 class=\"wp-block-heading ext-animate--on\">\ud83c\udfa8 Animaci\u00f3n y Creatividad Visual<\/h2>\n\n\n\n<p class=\"ext-animate--on\">Detr\u00e1s de cada video de humor absurdo, hay horas de edici\u00f3n y, en muchos casos, <strong>animaci\u00f3n propia<\/strong>. En El Canal del Wason, creemos que lo visual debe acompa\u00f1ar a la locura del guion. Usamos t\u00e9cnicas que recuerdan a la era dorada de los juegos Flash, con movimientos exagerados y expresiones que potencian el remate de cada chiste. Es un trabajo artesanal dise\u00f1ado para que cada \u00abplay\u00bb valga tu tiempo.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity ext-animate--on\"\/>\n\n\n\n<h2 class=\"wp-block-heading ext-animate--on\">\ud83d\udca1 El Consejo del Wason: C\u00f3mo Maximizar el Vicio<\/h2>\n\n\n\n<p class=\"ext-animate--on\">Para disfrutar de esta secci\u00f3n como un verdadero profesional, te recomendamos seguir este protocolo de visualizaci\u00f3n:<\/p>\n\n\n\n<ol start=\"1\" class=\"wp-block-list ext-animate--on\">\n<li class=\"ext-animate--on\"><strong>Suscribite con la Campanita:<\/strong> En YouTube, el algoritmo es un villano m\u00e1s dif\u00edcil de vencer que Thanos. La \u00fanica forma de asegurarte de que te avise cuando subo un video nuevo (o cuando estreno un juego ac\u00e1 en la web) es teniendo esa campana activada.<\/li>\n\n\n\n<li class=\"ext-animate--on\"><strong>El Loop Perfecto:<\/strong> Mir\u00e1 un video, re\u00edte un rato, y cuando te piquen los dedos de la manija, volv\u00e9 a la secci\u00f3n de <strong>Juegos de Mate<\/strong>. La risa te limpia la mente para que tus reflejos est\u00e9n al 100% para superar los r\u00e9cords de la comunidad.<\/li>\n\n\n\n<li class=\"ext-animate--on\"><strong>Particip\u00e1:<\/strong> \u00bfTen\u00e9s una idea para un doblaje bizarro? \u00bfQuer\u00e9s que bardeemos a alg\u00fan personaje en particular? Dejalo en los comentarios de YouTube. Muchos de los videos que ves ac\u00e1 nacieron de una sugerencia en el chat.<\/li>\n<\/ol>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity ext-animate--on\"\/>\n\n\n\n<h2 class=\"wp-block-heading ext-animate--on\">Conclusi\u00f3n: M\u00e1s que un Canal, una Forma de Ver el Mundo<\/h2>\n\n\n\n<p class=\"ext-animate--on\">Al final del d\u00eda, <strong>El Canal del Wason<\/strong> y esta web son dos caras de la misma moneda. Queremos que este sea tu refugio contra el aburrimiento. Un lugar donde no se juzga el humor \u00abnegro\u00bb, donde se celebra lo absurdo y donde siempre hay una comunidad lista para debatir si el Superman de Reeve le gana a Goku o por qu\u00e9 ese juego Flash de 2005 sigue siendo mejor que muchos juegos actuales.<\/p>\n\n\n\n<p class=\"ext-animate--on\">Acomodate, dale play a los videos que tenemos incrustados aqu\u00ed abajo para conocer la verdadera esencia del canal y no te olvides de ser parte de esta familia de locos. Despu\u00e9s de unas cuantas carcajadas, te espero en la secci\u00f3n de juegos para seguir demostrando qui\u00e9n manda en el ranking.<\/p>\n\n\n\n<p class=\"ext-animate--on\"><strong>\u00bfCu\u00e1l fue el video que m\u00e1s te hizo re\u00edr hoy?<\/strong> \u00a1Contalo en los comentarios de YouTube y compartilo con ese amigo que necesita un poco de caos en su vida!<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity ext-animate--on\"\/>\n\n\n\n<p class=\"has-text-align-center ext-animate--on\" style=\"margin-top:1.5rem\"><em>\u00bfTe quedaste con ganas de m\u00e1s? No dejes de visitar nuestros informes especiales sobre la historia de los videojuegos y el impacto de la IA en el entretenimiento de este 2026.<\/em><\/p>\n\n\n\n<div class=\"wp-block-columns alignwide ext-animate--on is-layout-flex wp-container-core-columns-is-layout-08c01c1c wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-stretch ext-animate--on is-layout-flow wp-container-core-column-is-layout-f5bb311e wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-style-ext-preset--group--natural-1--item-card-1--align-center ext-animate--on is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-default ext-animate--on is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image aligncenter size-large ext-aspect-landscape extendify-image-import ext-animate--on wp-duotone-varpresetduotoneprimary-foreground-1\"><img decoding=\"async\" src=\"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHdpZHRoPSI0OCIgaGVpZ2h0PSI0OCIgZmlsbD0iIzAwMDAwMCIgdmlld0JveD0iMCAwIDI1NiAyNTYiPjxwYXRoIGQ9Ik0xNzIsNzZhNDQsNDQsMCwxLDAtNDQsNDRBNDQuMDUsNDQuMDUsMCwwLDAsMTcyLDc2Wm0tNDQsMjhhMjgsMjgsMCwxLDEsMjgtMjhBMjgsMjgsMCwwLDEsMTI4LDEwNFptNjAsMjRhNDQsNDQsMCwxLDAsNDQsNDRBNDQuMDUsNDQuMDUsMCwwLDAsMTg4LDEyOFptMCw3MmEyOCwyOCwwLDEsMSwyOC0yOEEyOCwyOCwwLDAsMSwxODgsMjAwWk02OCwxMjhhNDQsNDQsMCwxLDAsNDQsNDRBNDQuMDUsNDQuMDUsMCwwLDAsNjgsMTI4Wm0wLDcyYTI4LDI4LDAsMSwxLDI4LTI4QTI4LDI4LDAsMCwxLDY4LDIwMFoiPjwvcGF0aD48L3N2Zz4=\" alt=\"\" style=\"object-fit:cover\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center ext-animate--on\">Video Destacado<\/h3>\n\n\n\n<p class=\"has-text-align-center ext-animate--on\">Sum\u00e9rgete en las mejores selecciones que te har\u00e1n re\u00edr y aprender mientras juegas.<\/p>\n\n\n\n<div class=\"wp-block-buttons ext-animate--on is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-ext-preset--button--natural-1--button-1 ext-animate--on\"><a class=\"wp-block-button__link wp-element-button\" href=\"#\">Ver videos<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch ext-animate--on is-layout-flow wp-container-core-column-is-layout-f5bb311e wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-style-ext-preset--group--natural-1--item-card-1--align-center ext-animate--on is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-default ext-animate--on is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image aligncenter size-large ext-aspect-landscape extendify-image-import ext-animate--on wp-duotone-varpresetduotoneprimary-foreground-2\"><img decoding=\"async\" src=\"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHdpZHRoPSI0OCIgaGVpZ2h0PSI0OCIgZmlsbD0iIzAwMDAwMCIgdmlld0JveD0iMCAwIDI1NiAyNTYiPjxwYXRoIGQ9Ik04MCw0MGE0MCw0MCwwLDEsMCw0MCw0MEE0MCw0MCwwLDAsMCw4MCw0MFptMCw2NGEyNCwyNCwwLDEsMSwyNC0yNEEyNCwyNCwwLDAsMSw4MCwxMDRabTk2LDE2YTQwLDQwLDAsMSwwLTQwLTQwQTQwLDQwLDAsMCwwLDE3NiwxMjBabTAtNjRhMjQsMjQsMCwxLDEtMjQsMjRBMjQsMjQsMCwwLDEsMTc2LDU2Wk04MCwxMzZhNDAsNDAsMCwxLDAsNDAsNDBBNDAsNDAsMCwwLDAsODAsMTM2Wm0wLDY0YTI0LDI0LDAsMSwxLDI0LTI0QTI0LDI0LDAsMCwxLDgwLDIwMFptOTYtNjRhNDAsNDAsMCwxLDAsNDAsNDBBNDAsNDAsMCwwLDAsMTc2LDEzNlptMCw2NGEyNCwyNCwwLDEsMSwyNC0yNEEyNCwyNCwwLDAsMSwxNzYsMjAwWiI+PC9wYXRoPjwvc3ZnPg==\" alt=\"\" style=\"object-fit:cover\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center ext-animate--on\">Lo M\u00e1s Nuevo<\/h3>\n\n\n\n<p class=\"has-text-align-center ext-animate--on\">Descubre las \u00faltimas subidas con contenido fresco y emocionante de El Canal del Wason.<\/p>\n\n\n\n<div class=\"wp-block-buttons ext-animate--on is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-ext-preset--button--natural-1--button-1 ext-animate--on\"><a class=\"wp-block-button__link wp-element-button\" href=\"#\">Ver videos<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch ext-animate--on is-layout-flow wp-container-core-column-is-layout-f5bb311e wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-style-ext-preset--group--natural-1--item-card-1--align-center ext-animate--on is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-default ext-animate--on is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image aligncenter size-large ext-aspect-landscape extendify-image-import ext-animate--on wp-duotone-varpresetduotoneprimary-foreground-3\"><img decoding=\"async\" src=\"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHdpZHRoPSI0OCIgaGVpZ2h0PSI0OCIgZmlsbD0iIzAwMDAwMCIgdmlld0JveD0iMCAwIDI1NiAyNTYiPjxwYXRoIGQ9Ik04MCw0MGE0MCw0MCwwLDEsMCw0MCw0MEE0MCw0MCwwLDAsMCw4MCw0MFptMCw2NGEyNCwyNCwwLDEsMSwyNC0yNEEyNCwyNCwwLDAsMSw4MCwxMDRabTk2LDE2YTQwLDQwLDAsMSwwLTQwLTQwQTQwLDQwLDAsMCwwLDE3NiwxMjBabTAtNjRhMjQsMjQsMCwxLDEtMjQsMjRBMjQsMjQsMCwwLDEsMTc2LDU2Wk04MCwxMzZhNDAsNDAsMCwxLDAsNDAsNDBBNDAsNDAsMCwwLDAsODAsMTM2Wm0wLDY0YTI0LDI0LDAsMSwxLDI0LTI0QTI0LDI0LDAsMCwxLDgwLDIwMFptMTM2LTI0YTgsOCwwLDAsMS04LDhIMTg0djI0YTgsOCwwLDAsMS0xNiwwVjE4NEgxNDRhOCw4LDAsMCwxLDAtMTZoMjRWMTQ0YTgsOCwwLDAsMSwxNiwwdjI0aDI0QTgsOCwwLDAsMSwyMTYsMTc2WiI+PC9wYXRoPjwvc3ZnPg==\" alt=\"\" style=\"object-fit:cover\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center ext-animate--on\">Cl\u00e1sicos del Canal<\/h3>\n\n\n\n<p class=\"has-text-align-center ext-animate--on\">Revive los videos m\u00e1s populares y entra\u00f1ables que han marcado la historia del canal.<\/p>\n\n\n\n<div class=\"wp-block-buttons ext-animate--on is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-ext-preset--button--natural-1--button-1 ext-animate--on\"><a class=\"wp-block-button__link wp-element-button\" href=\"#\">Ver videos<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Zona de Videos del Wason: Donde el Humor Absurdo y el Vicio se Encuentran En el vasto oc\u00e9ano de contenido que es internet en 2026, encontrar un lugar que combine la irreverencia, la nostalgia y el humor sin filtros es como encontrar un \u00abglitch\u00bb de dinero infinito en un RPG: dif\u00edcil, pero sumamente satisfactorio. Si [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-with-title","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-92","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Videos del Canal -<\/title>\n<meta name=\"description\" content=\"Mir\u00e1 los videos en la web o en nuestro canal de YouTube. \u00a1Suscribite al Canal del Wason y acept\u00e1 el reto de una mano!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/muyano.com\/elcanaldelwason\/videos-del-canal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Videos del Canal -\" \/>\n<meta property=\"og:description\" content=\"Mir\u00e1 los videos en la web o en nuestro canal de YouTube. \u00a1Suscribite al Canal del Wason y acept\u00e1 el reto de una mano!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/muyano.com\/elcanaldelwason\/videos-del-canal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T12:02:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/muyano.com\/elcanaldelwason\/wp-content\/uploads\/2026\/03\/con-el-mate.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1169\" \/>\n\t<meta property=\"og:image:height\" content=\"1999\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/videos-del-canal\\\/\",\"url\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/videos-del-canal\\\/\",\"name\":\"Videos del Canal -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/videos-del-canal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/videos-del-canal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/con-el-mate.png\",\"datePublished\":\"2026-03-15T22:59:43+00:00\",\"dateModified\":\"2026-03-20T12:02:42+00:00\",\"description\":\"Mir\u00e1 los videos en la web o en nuestro canal de YouTube. \u00a1Suscribite al Canal del Wason y acept\u00e1 el reto de una mano!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/videos-del-canal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/videos-del-canal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/videos-del-canal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/con-el-mate.png\",\"contentUrl\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/con-el-mate.png\",\"width\":1169,\"height\":1999},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/videos-del-canal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Videos del Canal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/#website\",\"url\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/\",\"name\":\"El Canal del Wason\",\"description\":\"Juegos online\",\"publisher\":{\"@id\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/#organization\",\"name\":\"El Canal del Wason\",\"url\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo-sin-fondo.png\",\"contentUrl\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Logo-sin-fondo.png\",\"width\":480,\"height\":197,\"caption\":\"El Canal del Wason\"},\"image\":{\"@id\":\"https:\\\/\\\/muyano.com\\\/elcanaldelwason\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Videos del Canal -","description":"Mir\u00e1 los videos en la web o en nuestro canal de YouTube. \u00a1Suscribite al Canal del Wason y acept\u00e1 el reto de una mano!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/muyano.com\/elcanaldelwason\/videos-del-canal\/","og_locale":"es_ES","og_type":"article","og_title":"Videos del Canal -","og_description":"Mir\u00e1 los videos en la web o en nuestro canal de YouTube. \u00a1Suscribite al Canal del Wason y acept\u00e1 el reto de una mano!","og_url":"https:\/\/muyano.com\/elcanaldelwason\/videos-del-canal\/","article_modified_time":"2026-03-20T12:02:42+00:00","og_image":[{"width":1169,"height":1999,"url":"https:\/\/muyano.com\/elcanaldelwason\/wp-content\/uploads\/2026\/03\/con-el-mate.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/muyano.com\/elcanaldelwason\/videos-del-canal\/","url":"https:\/\/muyano.com\/elcanaldelwason\/videos-del-canal\/","name":"Videos del Canal -","isPartOf":{"@id":"https:\/\/muyano.com\/elcanaldelwason\/#website"},"primaryImageOfPage":{"@id":"https:\/\/muyano.com\/elcanaldelwason\/videos-del-canal\/#primaryimage"},"image":{"@id":"https:\/\/muyano.com\/elcanaldelwason\/videos-del-canal\/#primaryimage"},"thumbnailUrl":"https:\/\/muyano.com\/elcanaldelwason\/wp-content\/uploads\/2026\/03\/con-el-mate.png","datePublished":"2026-03-15T22:59:43+00:00","dateModified":"2026-03-20T12:02:42+00:00","description":"Mir\u00e1 los videos en la web o en nuestro canal de YouTube. \u00a1Suscribite al Canal del Wason y acept\u00e1 el reto de una mano!","breadcrumb":{"@id":"https:\/\/muyano.com\/elcanaldelwason\/videos-del-canal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/muyano.com\/elcanaldelwason\/videos-del-canal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/muyano.com\/elcanaldelwason\/videos-del-canal\/#primaryimage","url":"https:\/\/muyano.com\/elcanaldelwason\/wp-content\/uploads\/2026\/03\/con-el-mate.png","contentUrl":"https:\/\/muyano.com\/elcanaldelwason\/wp-content\/uploads\/2026\/03\/con-el-mate.png","width":1169,"height":1999},{"@type":"BreadcrumbList","@id":"https:\/\/muyano.com\/elcanaldelwason\/videos-del-canal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/muyano.com\/elcanaldelwason\/"},{"@type":"ListItem","position":2,"name":"Videos del Canal"}]},{"@type":"WebSite","@id":"https:\/\/muyano.com\/elcanaldelwason\/#website","url":"https:\/\/muyano.com\/elcanaldelwason\/","name":"El Canal del Wason","description":"Juegos online","publisher":{"@id":"https:\/\/muyano.com\/elcanaldelwason\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/muyano.com\/elcanaldelwason\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/muyano.com\/elcanaldelwason\/#organization","name":"El Canal del Wason","url":"https:\/\/muyano.com\/elcanaldelwason\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/muyano.com\/elcanaldelwason\/#\/schema\/logo\/image\/","url":"https:\/\/muyano.com\/elcanaldelwason\/wp-content\/uploads\/2026\/03\/Logo-sin-fondo.png","contentUrl":"https:\/\/muyano.com\/elcanaldelwason\/wp-content\/uploads\/2026\/03\/Logo-sin-fondo.png","width":480,"height":197,"caption":"El Canal del Wason"},"image":{"@id":"https:\/\/muyano.com\/elcanaldelwason\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/muyano.com\/elcanaldelwason\/wp-json\/wp\/v2\/pages\/92","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/muyano.com\/elcanaldelwason\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/muyano.com\/elcanaldelwason\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/muyano.com\/elcanaldelwason\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/muyano.com\/elcanaldelwason\/wp-json\/wp\/v2\/comments?post=92"}],"version-history":[{"count":6,"href":"https:\/\/muyano.com\/elcanaldelwason\/wp-json\/wp\/v2\/pages\/92\/revisions"}],"predecessor-version":[{"id":178,"href":"https:\/\/muyano.com\/elcanaldelwason\/wp-json\/wp\/v2\/pages\/92\/revisions\/178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/muyano.com\/elcanaldelwason\/wp-json\/wp\/v2\/media\/90"}],"wp:attachment":[{"href":"https:\/\/muyano.com\/elcanaldelwason\/wp-json\/wp\/v2\/media?parent=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}